{"id":24398,"date":"2026-03-24T09:59:29","date_gmt":"2026-03-24T12:59:29","guid":{"rendered":"https:\/\/theme-dev.cmsmasters.net\/newspaper\/?p=24398"},"modified":"2026-06-02T09:22:07","modified_gmt":"2026-06-02T12:22:07","slug":"projeto-de-eficiencia-energetica-da-copel-moderniza-iluminacao-publica-em-francisco-beltrao-2","status":"publish","type":"post","link":"https:\/\/jornalopiniao.com.br\/pt\/projeto-de-eficiencia-energetica-da-copel-moderniza-iluminacao-publica-em-francisco-beltrao-2\/","title":{"rendered":"Projeto de efici\u00eancia energ\u00e9tica da Copel moderniza ilumina\u00e7\u00e3o p\u00fablica em Francisco Beltr\u00e3o"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/iluminacao-publica-800x445-1.jpg\" alt=\"\" class=\"wp-image-30883\" srcset=\"https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/iluminacao-publica-800x445-1.jpg 800w, https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/iluminacao-publica-800x445-1-300x167.jpg 300w, https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/iluminacao-publica-800x445-1-768x427.jpg 768w, https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/iluminacao-publica-800x445-1-18x10.jpg 18w, https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/iluminacao-publica-800x445-1-539x300.jpg 539w, https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/iluminacao-publica-800x445-1-600x334.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n<p><em>Viabilizada pela Companhia Paranaense de Energia, a iniciativa vai instalar 2,7 mil pontos de luz na cidade at\u00e9 dezembro de 2022, com investimento total de R$ 5,19 milh\u00f5es.<\/em><\/p>\n<p>Com recursos do Programa de Efici\u00eancia Energ\u00e9tica (PEE), um projeto est\u00e1 promovendo a troca de l\u00e2mpadas antigas por unidades de LED em Francisco Beltr\u00e3o, no Sudoeste do Estado. Viabilizada pela Copel, a iniciativa vai instalar 2,7 mil\u00a0pontos de luz na cidade at\u00e9 dezembro de 2022, com investimento total de R$ 5,19 milh\u00f5es.<\/p>\n<p>As novas l\u00e2mpadas ajudam a reduzir o consumo de energia el\u00e9trica e conferem maior seguran\u00e7a para a popula\u00e7\u00e3o, al\u00e9m contribuir para preservar o meio ambiente.<\/p>\n<p>O uso dos equipamentos de ilumina\u00e7\u00e3o com tecnologia LED vai permitir a redu\u00e7\u00e3o de 405,81 kilowatts (kW) nos hor\u00e1rios de ponta, quando a demanda por energia \u00e9 maior. Ao final de um ano, o consumo de energia el\u00e9trica da instala\u00e7\u00e3o ser\u00e1 reduzido em aproximadamente 2.600 kilowatts\/hora (MWh), o que representa todo o consumo residencial anual de uma cidade do porte de Nova Laranjeiras.\u00a0<\/p>\n<p>Al\u00e9m de mais eficientes, as lumin\u00e1rias novas t\u00eam vida \u00fatil at\u00e9 30 vezes maior do que os modelos antigos, n\u00e3o emitem raios ultravioleta e n\u00e3o utilizam metais pesados, como o merc\u00fario, em sua composi\u00e7\u00e3o. At\u00e9 o final do projeto, mais de 70 ruas e avenidas de Francisco Beltr\u00e3o ser\u00e3o beneficiadas pelas novas l\u00e2mpadas.\u00a0\u00a0<\/p>\n<p><strong>DESCARTE ADEQUADO\u00a0<\/strong>\u2013\u00a0Ap\u00f3s a retirada, todos os equipamentos antigos ser\u00e3o descartados e seus res\u00edduos destinados de maneira adequada, conforme estabelece a Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos. Para incentivar a economia circular, as caixas de papel\u00e3o, os revestimentos de pl\u00e1stico, isopor, alum\u00ednio e a\u00e7o ser\u00e3o destinados \u00e0 reciclagem.<\/p>\n<p>O projeto deve, ainda, chegar a outras quatro cidades do interior do Estado, selecionadas atrav\u00e9s da Chamada P\u00fablica n\u00ba 003\/2020. S\u00e3o elas: Cambar\u00e1, Santo Ant\u00f4nio da Platina, Mandaguari e Irati. No momento, todas est\u00e3o em fase de contrata\u00e7\u00e3o dos materiais e servi\u00e7os.<\/p>\n<p><strong>CONSUMO CONSCIENTE<\/strong>\u00a0\u2013 O Programa de Efici\u00eancia Energ\u00e9tica tem como objetivo promover o consumo consciente e combater o desperd\u00edcio da energia el\u00e9trica em todos os setores da economia. Isto ocorre por meio do incentivo e financiamento de projetos que demonstrem a import\u00e2ncia e a viabilidade econ\u00f4mica de melhoria da efici\u00eancia energ\u00e9tica de equipamentos, processos e usos finais de energia.Na Copel, em 20 anos de atividades o programa j\u00e1 investiu mais de R$ 530 milh\u00f5es na execu\u00e7\u00e3o de projetos em todos os munic\u00edpios da \u00e1rea de concess\u00e3o da distribuidora.<\/p>\n<p>Os benef\u00edcios contemplam diversas classes de consumo, entre elas as fam\u00edlias de baixa renda e a \u00e1rea dos servi\u00e7os p\u00fablicos, com a troca de equipamentos em hospitais, institui\u00e7\u00f5es beneficentes, universidades e escolas p\u00fablicas.<\/p>\n<p>Outra frente \u00e9 a moderniza\u00e7\u00e3o da ilumina\u00e7\u00e3o p\u00fablica, com a destina\u00e7\u00e3o de recursos a mais de 300 munic\u00edpios ao longo destas duas d\u00e9cadas. Os investimentos em efici\u00eancia energ\u00e9tica s\u00e3o orientados por diretrizes estabelecidas pela Ag\u00eancia Nacional de Energia El\u00e9trica (ANEEL)<\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Viabilizada pela Companhia Paranaense de Energia, a iniciativa vai instalar 2,7 mil pontos de luz na cidade at\u00e9 dezembro de 2022, com investimento total de R$ 5,19 milh\u00f5es.<\/p>","protected":false},"author":22,"featured_media":30883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[99],"tags":[75,76],"post_template":[83],"top_category":[],"class_list":["post-24398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-work","tag-world","post_template-layout-padrao","pmpro-has-access"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/posts\/24398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/comments?post=24398"}],"version-history":[{"count":3,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/posts\/24398\/revisions"}],"predecessor-version":[{"id":30885,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/posts\/24398\/revisions\/30885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/media\/30883"}],"wp:attachment":[{"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/media?parent=24398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/categories?post=24398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/tags?post=24398"},{"taxonomy":"post_template","embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/post_template?post=24398"},{"taxonomy":"top_category","embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/top_category?post=24398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}