{"id":1405,"date":"2026-03-24T09:59:29","date_gmt":"2026-03-24T12:59:29","guid":{"rendered":"https:\/\/theme-dev.cmsmasters.net\/medical\/?p=1335"},"modified":"2026-06-02T09:22:07","modified_gmt":"2026-06-02T12:22:07","slug":"parana-recebe-332-mil-vacinas-contra-a-gripe-para-inicio-da-campanha-no-proximo-sabado","status":"publish","type":"post","link":"https:\/\/jornalopiniao.com.br\/pt\/parana-recebe-332-mil-vacinas-contra-a-gripe-para-inicio-da-campanha-no-proximo-sabado\/","title":{"rendered":"Paran\u00e1 recebe 332 mil vacinas contra a gripe para in\u00edcio da campanha no pr\u00f3ximo s\u00e1bado"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/vacina-1-800x445-1.webp\" alt=\"\" class=\"wp-image-30928\" srcset=\"https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/vacina-1-800x445-1.webp 800w, https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/vacina-1-800x445-1-300x167.webp 300w, https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/vacina-1-800x445-1-768x427.webp 768w, https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/vacina-1-800x445-1-18x10.webp 18w, https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/vacina-1-800x445-1-539x300.webp 539w, https:\/\/jornalopiniao.com.br\/wp-content\/uploads\/2026\/03\/vacina-1-800x445-1-600x334.webp 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n<p>O Paran\u00e1 recebeu neste s\u00e1bado (21) 332 mil vacinas contra a gripe (influenza), destinadas para o in\u00edcio da campanha de refor\u00e7o da vacina\u00e7\u00e3o para o p\u00fablico-alvo. As doses foram entregues \u00e0 Secretaria de Estado da Sa\u00fade (Sesa) e est\u00e3o armazenadas no Centro de Medicamentos do Paran\u00e1 (Cemepar). A distribui\u00e7\u00e3o \u00e0s Regionais de Sa\u00fade deve iniciar segunda-feira (23).\u00a0<br \/><br \/><\/p>\n<p class=\"has-cm-color-6-color has-text-color has-link-color has-medium-font-size wp-elements-40bb820ed7e320c69bf0e1e9cfa7bb4e\">A meta \u00e9 imunizar 90% de cada um dos grupos priorit\u00e1rios para vacina\u00e7\u00e3o de rotina contra influenza, que incluem: crian\u00e7as de 6 meses a menores de 6 anos, idosos com mais de 60 anos e gestantes. A vacina tamb\u00e9m ser\u00e1 ofertada a outros grupos priorit\u00e1rios.\u00a0<\/p>\n<p class=\"has-cm-color-6-color has-text-color has-link-color has-medium-font-size wp-elements-1300665f729bce085c17e30695666521\">As doses s\u00e3o usadas no in\u00edcio da 28.\u00aa Campanha Nacional de Vacina\u00e7\u00e3o contra a influenza, que acontece a partir do pr\u00f3ximo s\u00e1bado, (28\/03). A estimativa \u00e9 vacinar 4.592.615 pessoas, no Paran\u00e1.\u00a0<\/p>\n<p class=\"has-cm-color-6-color has-text-color has-link-color has-medium-font-size wp-elements-3188067b88f51cee7d742535ec4033be\">\u201cVacinar-se contra a gripe \u00e9 um ato de prote\u00e7\u00e3o individual e coletiva. Receber a vacina auxilia na redu\u00e7\u00e3o de complica\u00e7\u00f5es, das interna\u00e7\u00f5es e da mortalidade decorrentes das infec\u00e7\u00f5es pelo v\u00edrus influenza na popula\u00e7\u00e3o-alvo\u201d, ressaltou o secret\u00e1rio de Estado da Sa\u00fade, Beto Preto.<\/p>\n<p class=\"has-cm-color-6-color has-text-color has-link-color has-medium-font-size wp-elements-4dbff68ec18b8cb3ce7de9ad3f60214d\">Cada frasco cont\u00e9m 10 doses e ser\u00e3o distribu\u00eddas \u00e0s Regionais de Sa\u00fade conforme a estimativa populacional de cada regi\u00e3o. Cada frasco cont\u00e9m 10 doses de 0,5ml e pode ser administrada na mesma ocasi\u00e3o de outras vacinas do Calend\u00e1rio Nacional de Vacina\u00e7\u00e3o e com outros medicamentos.<\/p>\n<p class=\"has-cm-color-6-color has-text-color has-link-color has-medium-font-size wp-elements-f326bb422d81ee4933b97b4ba1c9a961\">Recomenda-se adiar a aplica\u00e7\u00e3o caso a pessoa apresente quadro de doen\u00e7as febres agudas, moderadas ou graves, ou caso confirmado de Covid-19 (RT- PCR e TR Ag), devendo-se vacinar ap\u00f3s a melhora dos sintomas.<\/p>","protected":false},"excerpt":{"rendered":"<p>A meta \u00e9 imunizar 90% de cada um dos grupos priorit\u00e1rios para vacina\u00e7\u00e3o de rotina contra influenza. Foto: SESA<\/p>","protected":false},"author":22,"featured_media":30928,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[98,102,97],"tags":[],"post_template":[83],"top_category":[82],"class_list":["post-1405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-saude","category-seguranca","post_template-layout-padrao","top_category-noticia","pmpro-has-access"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/posts\/1405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/comments?post=1405"}],"version-history":[{"count":3,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/posts\/1405\/revisions"}],"predecessor-version":[{"id":30932,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/posts\/1405\/revisions\/30932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/media\/30928"}],"wp:attachment":[{"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/media?parent=1405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/categories?post=1405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/tags?post=1405"},{"taxonomy":"post_template","embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/post_template?post=1405"},{"taxonomy":"top_category","embeddable":true,"href":"https:\/\/jornalopiniao.com.br\/pt\/wp-json\/wp\/v2\/top_category?post=1405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}